{"id":2477,"date":"2023-05-23T19:11:43","date_gmt":"2023-05-23T17:11:43","guid":{"rendered":"https:\/\/www.zallabai.net\/?page_id=2477"},"modified":"2023-05-24T09:43:00","modified_gmt":"2023-05-24T07:43:00","slug":"programa-electoral-2023","status":"publish","type":"page","link":"https:\/\/www.zallabai.net\/eu_eu\/elecciones-2023\/programa-electoral-2023\/","title":{"rendered":"Programa Electoral 2023"},"content":{"rendered":"<hr class=\"wp-block-separator has-css-opacity\"\/>\n\n\n<h1 style=\"text-align: center;\"><strong><em>ELECCIONES 2023<\/em><\/strong><\/h1>\n\n\n<hr class=\"wp-block-separator has-css-opacity\"\/>\n\n\n<div id=\"pl-gb2477-6a046570cae9a\"  class=\"panel-layout\" ><div id=\"pg-gb2477-6a046570cae9a-0\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-gb2477-6a046570cae9a-0-0\"  class=\"panel-grid-cell\" ><div id=\"panel-gb2477-6a046570cae9a-0-0-0\" class=\"so-panel widget widget_themegrill_flash_service tg-widget tg-single-service panel-first-child panel-last-child\" data-index=\"0\" >\n<div class=\"tg-service-widget tg-service-layout-2\">\n\t<div class=\"service-wrapper\">\n\t\t<div class=\"service-icon-title-wrapper clearfix\">\n\t\t\t\t\t\t<div class=\"service-icon-wrap\"><i class=\"fa fa-book\"><\/i><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n<\/div>\n<\/div><\/div><\/div><\/div>\n\n\n<h2 class=\"wp-block-heading has-text-align-center\"><a href=\"https:\/\/www.zallabai.net\/wp-content\/uploads\/2023\/05\/ZALLABAI_PROGRAMA2023_CAS.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">Hauteskunde Programa<\/a><\/h2>\n\n\n\n<div style=\"height:13px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n<div id=\"pl-gb2477-6a046570cbad8\"  class=\"panel-layout\" ><div id=\"pg-gb2477-6a046570cbad8-0\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-gb2477-6a046570cbad8-0-0\"  class=\"panel-grid-cell panel-grid-cell-empty\" ><\/div><div id=\"pgc-gb2477-6a046570cbad8-0-1\"  class=\"panel-grid-cell panel-grid-cell-mobile-last\" ><div id=\"panel-gb2477-6a046570cbad8-0-1-0\" class=\"so-panel widget widget_sow-image panel-first-child panel-last-child\" data-index=\"0\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-image so-widget-sow-image-default-aacfc7854b76-2477\"\n\t\t\t\n\t\t>\n<div class=\"sow-image-container\">\n\t\t\t<a href=\"https:\/\/www.zallabai.net\/wp-content\/uploads\/2023\/05\/ZALLABAI_PROGRAMA2023_CAS.pdf\"\n\t\t\ttarget=\"_blank\" rel=\"noopener noreferrer\" \t\t>\n\t\t\t<img \n\tsrc=\"https:\/\/www.zallabai.net\/wp-content\/uploads\/2023\/05\/PORTADA_CAS-1103x1536.png\" width=\"1103\" height=\"1536\" srcset=\"https:\/\/www.zallabai.net\/wp-content\/uploads\/2023\/05\/PORTADA_CAS-1103x1536.png 1103w, https:\/\/www.zallabai.net\/wp-content\/uploads\/2023\/05\/PORTADA_CAS-215x300.png 215w, https:\/\/www.zallabai.net\/wp-content\/uploads\/2023\/05\/PORTADA_CAS-735x1024.png 735w, https:\/\/www.zallabai.net\/wp-content\/uploads\/2023\/05\/PORTADA_CAS-768x1069.png 768w, https:\/\/www.zallabai.net\/wp-content\/uploads\/2023\/05\/PORTADA_CAS-1471x2048.png 1471w, https:\/\/www.zallabai.net\/wp-content\/uploads\/2023\/05\/PORTADA_CAS-9x12.png 9w, https:\/\/www.zallabai.net\/wp-content\/uploads\/2023\/05\/PORTADA_CAS.png 1866w\" sizes=\"(max-width: 1103px) 100vw, 1103px\" title=\"PROGRAMA ELECTORAL 2023 CAS\" alt=\"\" \t\tclass=\"so-widget-image\"\/>\n\t\t\t<\/a><\/div>\n\n<\/div><\/div><\/div><div id=\"pgc-gb2477-6a046570cbad8-0-2\"  class=\"panel-grid-cell panel-grid-cell-empty\" ><\/div><\/div><\/div>\n\n\n<div style=\"height:21px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\"><a href=\"https:\/\/www.zallabai.net\/wp-content\/uploads\/2023\/05\/ZALLABAI_PROGRAMA2023_EUS.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">Haustekunde Programa<\/a><\/h2>\n\n\n\n<div style=\"height:13px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n<div id=\"pl-gb2477-6a046570cc3f6\"  class=\"panel-layout\" ><div id=\"pg-gb2477-6a046570cc3f6-0\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-gb2477-6a046570cc3f6-0-0\"  class=\"panel-grid-cell panel-grid-cell-empty\" ><\/div><div id=\"pgc-gb2477-6a046570cc3f6-0-1\"  class=\"panel-grid-cell panel-grid-cell-mobile-last\" ><div id=\"panel-gb2477-6a046570cc3f6-0-1-0\" class=\"so-panel widget widget_sow-image panel-first-child panel-last-child\" data-index=\"0\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-image so-widget-sow-image-default-aacfc7854b76-2477\"\n\t\t\t\n\t\t>\n<div class=\"sow-image-container\">\n\t\t\t<a href=\"https:\/\/www.zallabai.net\/wp-content\/uploads\/2023\/05\/ZALLABAI_PROGRAMA2023_EUS.pdf\"\n\t\t\ttarget=\"_blank\" rel=\"noopener noreferrer\" \t\t>\n\t\t\t<img \n\tsrc=\"https:\/\/www.zallabai.net\/wp-content\/uploads\/2023\/05\/PORTADA_EUS-1103x1536.png\" width=\"1103\" height=\"1536\" srcset=\"https:\/\/www.zallabai.net\/wp-content\/uploads\/2023\/05\/PORTADA_EUS-1103x1536.png 1103w, https:\/\/www.zallabai.net\/wp-content\/uploads\/2023\/05\/PORTADA_EUS-215x300.png 215w, https:\/\/www.zallabai.net\/wp-content\/uploads\/2023\/05\/PORTADA_EUS-735x1024.png 735w, https:\/\/www.zallabai.net\/wp-content\/uploads\/2023\/05\/PORTADA_EUS-768x1069.png 768w, https:\/\/www.zallabai.net\/wp-content\/uploads\/2023\/05\/PORTADA_EUS-1471x2048.png 1471w, https:\/\/www.zallabai.net\/wp-content\/uploads\/2023\/05\/PORTADA_EUS-9x12.png 9w, https:\/\/www.zallabai.net\/wp-content\/uploads\/2023\/05\/PORTADA_EUS.png 1866w\" sizes=\"(max-width: 1103px) 100vw, 1103px\" title=\"HAUTESKUNDE PROGRAMA 2023 EUS\" alt=\"\" \t\tclass=\"so-widget-image\"\/>\n\t\t\t<\/a><\/div>\n\n<\/div><\/div><\/div><div id=\"pgc-gb2477-6a046570cc3f6-0-2\"  class=\"panel-grid-cell panel-grid-cell-empty\" ><\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>ELECCIONES 2023 Programa Electoral Haustekunde Programa<\/p>","protected":false},"author":1,"featured_media":0,"parent":2087,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Zalla Bai - Programa Electoral 2023<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.zallabai.net\/eu_eu\/elecciones-2023\/programa-electoral-2023\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Zalla Bai - Programa Electoral 2023\" \/>\n<meta property=\"og:description\" content=\"ELECCIONES 2023 Programa Electoral Haustekunde Programa\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.zallabai.net\/eu_eu\/elecciones-2023\/programa-electoral-2023\/\" \/>\n<meta property=\"og:site_name\" content=\"Zalla Bai\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/zalla.bai\" \/>\n<meta property=\"article:modified_time\" content=\"2023-05-24T07:43:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.zallabai.net\/wp-content\/uploads\/2023\/05\/PORTADA_CAS-1103x1536.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@zallabai\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minutua\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.zallabai.net\/elecciones-2023\/programa-electoral-2023\/\",\"url\":\"https:\/\/www.zallabai.net\/elecciones-2023\/programa-electoral-2023\/\",\"name\":\"Zalla Bai - Programa Electoral 2023\",\"isPartOf\":{\"@id\":\"https:\/\/www.zallabai.net\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.zallabai.net\/elecciones-2023\/programa-electoral-2023\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.zallabai.net\/elecciones-2023\/programa-electoral-2023\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.zallabai.net\/wp-content\/uploads\/2023\/05\/PORTADA_CAS-1103x1536.png\",\"datePublished\":\"2023-05-23T17:11:43+00:00\",\"dateModified\":\"2023-05-24T07:43:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.zallabai.net\/elecciones-2023\/programa-electoral-2023\/#breadcrumb\"},\"inLanguage\":\"eu\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.zallabai.net\/elecciones-2023\/programa-electoral-2023\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"eu\",\"@id\":\"https:\/\/www.zallabai.net\/elecciones-2023\/programa-electoral-2023\/#primaryimage\",\"url\":\"https:\/\/www.zallabai.net\/wp-content\/uploads\/2023\/05\/PORTADA_CAS-1103x1536.png\",\"contentUrl\":\"https:\/\/www.zallabai.net\/wp-content\/uploads\/2023\/05\/PORTADA_CAS-1103x1536.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.zallabai.net\/elecciones-2023\/programa-electoral-2023\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.zallabai.net\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Elecciones 2023\",\"item\":\"https:\/\/www.zallabai.net\/elecciones-2023\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Programa Electoral 2023\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.zallabai.net\/#website\",\"url\":\"https:\/\/www.zallabai.net\/\",\"name\":\"Zalla Bai\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.zallabai.net\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.zallabai.net\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"eu\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.zallabai.net\/#organization\",\"name\":\"Zalla Bai\",\"url\":\"https:\/\/www.zallabai.net\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"eu\",\"@id\":\"https:\/\/www.zallabai.net\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.zallabai.net\/wp-content\/uploads\/2019\/02\/cropped-logo-blog2-1-1.png\",\"contentUrl\":\"https:\/\/www.zallabai.net\/wp-content\/uploads\/2019\/02\/cropped-logo-blog2-1-1.png\",\"width\":200,\"height\":56,\"caption\":\"Zalla Bai\"},\"image\":{\"@id\":\"https:\/\/www.zallabai.net\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/zalla.bai\",\"https:\/\/x.com\/zallabai\",\"https:\/\/www.instagram.com\/zallabai\/\",\"https:\/\/www.youtube.com\/channel\/UCuil7llKvOhvalYaJ1A_w7w\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Zalla Bai - Programa Electoral 2023","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.zallabai.net\/eu_eu\/elecciones-2023\/programa-electoral-2023\/","og_locale":"en_US","og_type":"article","og_title":"Zalla Bai - Programa Electoral 2023","og_description":"ELECCIONES 2023 Programa Electoral Haustekunde Programa","og_url":"https:\/\/www.zallabai.net\/eu_eu\/elecciones-2023\/programa-electoral-2023\/","og_site_name":"Zalla Bai","article_publisher":"https:\/\/www.facebook.com\/zalla.bai","article_modified_time":"2023-05-24T07:43:00+00:00","og_image":[{"url":"https:\/\/www.zallabai.net\/wp-content\/uploads\/2023\/05\/PORTADA_CAS-1103x1536.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_site":"@zallabai","twitter_misc":{"Est. reading time":"1 minutua"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.zallabai.net\/elecciones-2023\/programa-electoral-2023\/","url":"https:\/\/www.zallabai.net\/elecciones-2023\/programa-electoral-2023\/","name":"Zalla Bai - Programa Electoral 2023","isPartOf":{"@id":"https:\/\/www.zallabai.net\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.zallabai.net\/elecciones-2023\/programa-electoral-2023\/#primaryimage"},"image":{"@id":"https:\/\/www.zallabai.net\/elecciones-2023\/programa-electoral-2023\/#primaryimage"},"thumbnailUrl":"https:\/\/www.zallabai.net\/wp-content\/uploads\/2023\/05\/PORTADA_CAS-1103x1536.png","datePublished":"2023-05-23T17:11:43+00:00","dateModified":"2023-05-24T07:43:00+00:00","breadcrumb":{"@id":"https:\/\/www.zallabai.net\/elecciones-2023\/programa-electoral-2023\/#breadcrumb"},"inLanguage":"eu","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.zallabai.net\/elecciones-2023\/programa-electoral-2023\/"]}]},{"@type":"ImageObject","inLanguage":"eu","@id":"https:\/\/www.zallabai.net\/elecciones-2023\/programa-electoral-2023\/#primaryimage","url":"https:\/\/www.zallabai.net\/wp-content\/uploads\/2023\/05\/PORTADA_CAS-1103x1536.png","contentUrl":"https:\/\/www.zallabai.net\/wp-content\/uploads\/2023\/05\/PORTADA_CAS-1103x1536.png"},{"@type":"BreadcrumbList","@id":"https:\/\/www.zallabai.net\/elecciones-2023\/programa-electoral-2023\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.zallabai.net\/"},{"@type":"ListItem","position":2,"name":"Elecciones 2023","item":"https:\/\/www.zallabai.net\/elecciones-2023\/"},{"@type":"ListItem","position":3,"name":"Programa Electoral 2023"}]},{"@type":"WebSite","@id":"https:\/\/www.zallabai.net\/#website","url":"https:\/\/www.zallabai.net\/","name":"Zalla Bai","description":"","publisher":{"@id":"https:\/\/www.zallabai.net\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.zallabai.net\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"eu"},{"@type":"Organization","@id":"https:\/\/www.zallabai.net\/#organization","name":"Zalla Bai","url":"https:\/\/www.zallabai.net\/","logo":{"@type":"ImageObject","inLanguage":"eu","@id":"https:\/\/www.zallabai.net\/#\/schema\/logo\/image\/","url":"https:\/\/www.zallabai.net\/wp-content\/uploads\/2019\/02\/cropped-logo-blog2-1-1.png","contentUrl":"https:\/\/www.zallabai.net\/wp-content\/uploads\/2019\/02\/cropped-logo-blog2-1-1.png","width":200,"height":56,"caption":"Zalla Bai"},"image":{"@id":"https:\/\/www.zallabai.net\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/zalla.bai","https:\/\/x.com\/zallabai","https:\/\/www.instagram.com\/zallabai\/","https:\/\/www.youtube.com\/channel\/UCuil7llKvOhvalYaJ1A_w7w"]}]}},"_links":{"self":[{"href":"https:\/\/www.zallabai.net\/eu_eu\/wp-json\/wp\/v2\/pages\/2477"}],"collection":[{"href":"https:\/\/www.zallabai.net\/eu_eu\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.zallabai.net\/eu_eu\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.zallabai.net\/eu_eu\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.zallabai.net\/eu_eu\/wp-json\/wp\/v2\/comments?post=2477"}],"version-history":[{"count":25,"href":"https:\/\/www.zallabai.net\/eu_eu\/wp-json\/wp\/v2\/pages\/2477\/revisions"}],"predecessor-version":[{"id":2520,"href":"https:\/\/www.zallabai.net\/eu_eu\/wp-json\/wp\/v2\/pages\/2477\/revisions\/2520"}],"up":[{"embeddable":true,"href":"https:\/\/www.zallabai.net\/eu_eu\/wp-json\/wp\/v2\/pages\/2087"}],"wp:attachment":[{"href":"https:\/\/www.zallabai.net\/eu_eu\/wp-json\/wp\/v2\/media?parent=2477"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}